{"id":178569,"date":"2016-09-26T20:11:22","date_gmt":"2016-09-26T23:11:22","guid":{"rendered":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/"},"modified":"2024-11-08T10:31:23","modified_gmt":"2024-11-08T13:31:23","slug":"cuidados-com-rosas","status":"publish","type":"post","link":"https:\/\/www.trapp.com.br\/en\/cuidados-com-rosas\/","title":{"rendered":"Cuidados com Rosas"},"content":{"rendered":"<div class=\"head-interna\"><span class=\"date\">segunda, 26 de setembro de 2016<\/span><\/div>\n<div class=\"texto full-text\">\n<p>Texto e Foto: Christiane Calderan &#8211; Publicado por Raquel Patro no site O Jardineiro.net<\/p>\n<p>Podar envolve a remo\u00e7\u00e3o de qualquer rosa danificada, doente ou morta, para aprimorar a apar\u00eancia, estimulando o crescimento e o controle de pestes e doen\u00e7as. Podar de um jeito impr\u00f3prio ou erroneamente poder\u00e1 afetar a flora\u00e7\u00e3o e o crescimento. O \u201ccomo e quando\u201d de cort\u00e1-las \u00e9 determinado pelo tipo da mesma. Aqui irei dar alguns passos b\u00e1sicos para aparar sua rosa.<\/p>\n<p>As plantas estar\u00e3o prontas para serem podadas quando o arbusto come\u00e7ar a ficar sem folhas, ou ent\u00e3o com algumas folhas durante a esta\u00e7\u00e3o de inverno. Use uma faca afiada ou tesouras de poda e lembre-se de que dever\u00e1 cort\u00e1-las aproximadamente a um cent\u00edmentro abaixo do bot\u00e3o de rosa. Remova todas os cabinhos velhos, doentes ou danificados. Tire fora os caules que atravessam direto ao centro e reduza o centro da planta.<\/p>\n<p>Reduza em 1\/3 a parte crescida na \u00faltima esta\u00e7\u00e3o. Os cortes finais ajudam a determinar a forma da planta. Depois que limpar o resto da sujeira na planta, cheque se h\u00e1 insetos ou algum tipo de doen\u00e7a.<br \/>\nFertiliza\u00e7\u00e3o<\/p>\n<p>Ainda que algumas roseiras possam florescer sem fertiliza\u00e7\u00e3o, elas precisam dos nutrientes para chegar ao m\u00e1ximo de sua performance. Ent\u00e3o, para isto se torna necess\u00e1ria a aplica\u00e7\u00e3o de fertilizantes de sua prefer\u00eancia. Os tr\u00eas nutrientes b\u00e1sicos para um crescimento saud\u00e1vel de qualquer tipo de planta s\u00e3o: Nitrog\u00eanio, F\u00f3sforo e Pot\u00e1ssio.<\/p>\n<p>N\u00e3o fertilize novamente as rosas at\u00e9 que os bot\u00f5es flores\u00e7am. Se voc\u00ea quer evitar usar fertilizantes qu\u00edmicos, pode tentar as seguintes alternativas org\u00e2nicas: Torta de mamona, farinha de ossos, esterco curtido, cinzas sem sal, compostos org\u00e2nicos, emuls\u00e3o de peixe (adubo feito com \u00e1gua de aqu\u00e1rio mais resto composto de peixes de \u00e1gua doce), adubo comum, h\u00famus de minhoca, alga marinha ou adubo vegetal. Se voc\u00ea for utilizar fertilizantes qu\u00edmicos, dever\u00e1 seguir as instru\u00e7\u00f5es de aplica\u00e7\u00e3o e dosagem na embalagem do produto.<\/p>\n<p>Para fertilizantes qu\u00edmicos: Somente aplique fertilizante quando observar novos desenvolvimentos em sua rosa. Depois fa\u00e7a uma segunda aplica\u00e7\u00e3o somente quando a rosa come\u00e7ar a brotar, ent\u00e3o aplique uma fertiliza\u00e7\u00e3o final depois de dois meses.<\/p>\n<p><strong>Irriga\u00e7\u00e3o<\/strong><\/p>\n<p>A quantia e a freq\u00fc\u00eancia de irriga\u00e7\u00e3o ir\u00e3o depender to tipo de solo, tamanho do arbusto, e da precipita\u00e7\u00e3o pluviom\u00e9trica de sua \u00e1rea. Se voc\u00ea vive em uma \u00e1rea empoeirada, dever\u00e1 limpar as folhas de sua rosa pelo menos uma vez por semana (voc\u00ea ir\u00e1 faz\u00ea-las um grande favor!), e isso tamb\u00e9m ajuda a retirar pequenos insetos que grudam debaixo das folhagens. Alguns outros tipos de rosas precisam de irriga\u00e7\u00e3o toda manh\u00e3, mas evitando que deixe cair gotinhas de \u00e1gua nos bot\u00f5es e na folhagem, e providenciando forra\u00e7\u00e3o na base de sua planta, para que o solo segure a umidade.<\/p>\n<p>O uso da forra\u00e7\u00e3o em volta das roseiras ajuda a deixar o solo umedecido, e tamb\u00e9m atrasa o crescimento das ervas daninhas. A forra\u00e7\u00e3o pode ser feita de muitos materiais, como: Peda\u00e7os de madeiras, palhas ou grama seca recortada em pedacinhos. Materiais decorativos como madeira dura retalhada, casca de pinus, casca de coco podem ser usadas tamb\u00e9m. Quando aplicar qualquer forra\u00e7\u00e3o, n\u00e3o amontoe na base dos caules, e sim espalhe por todo o vaso, com mais ou menos 3,4 cent\u00edmetros de espessura (Sempre recoloque caso precise!).<br \/>\nPragas e Doen\u00e7as<\/p>\n<p>Insetos e doen\u00e7as nas folhagens poder\u00e3o afetar suas rosas. Existem tr\u00eas tipos de problemas, a saber: Fungos, poeira e ferrugem. Para os fungos, voc\u00ea dever\u00e1 limpar perfeitamente os restos de folhagem velha ca\u00eddas durante as podas, e pulverizar com um fungicida que voc\u00ea tenha prefer\u00eancia.<\/p>\n<p>O saneamento do jardim \u00e9 a melhor maneira de acabar com a ferrugem que pode surgir em suas folhas e pode ser controlada com fungicida. Insetos e \u00e1caros, como pulg\u00f5es, tripes, besouros, larvas, moscas, lagartas e vermes, tamb\u00e9m causam problemas em suas plantas. Os \u00c1caros s\u00e3o os que mais causam danos \u00e0s rosas. Os inimigos naturais dos \u00e1caros e muito bem recomendados s\u00e3o as joaninhas. Elas comem os pulg\u00f5es, que consequentemente poderiam deixar suas flores murchas e deformadas. Os pulg\u00f5es gostam de sugar a seiva das plantas, e produzem uma excre\u00e7\u00e3o levemente doce que atraem formigas, outras inimigas das plantas.<\/p>\n<p>Para um melhor controle de besouros, lagartas e vermes mate-as manualmente usando luvas. Os tripes deformam as p\u00e9talas das rosas. Para control\u00e1-las use inseticida debaixo das p\u00e9talas, fazendo uma certa cobertura para todas as p\u00e9talas e bot\u00f5es abertos. O controle \u00e9 f\u00e1cil e a pr\u00e1tica da preven\u00e7\u00e3o, com o uso regular dos produtos adequados, controla a maioria dos problemas com fungos, \u00e1caros e insetos.<\/p>\n<p>Dispon\u00edvel em\u00a0<a href=\"http:\/\/www.jardineiro.net\/cuidados-com-rosas.html\">O Jardineiro.net<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>segunda, 26 de setembro de 2016 Texto e Foto: Christiane Calderan &#8211; Publicado por Raquel Patro no site O Jardineiro.net Podar envolve a remo\u00e7\u00e3o de qualquer rosa danificada, doente ou morta, para aprimorar a apar\u00eancia, estimulando o crescimento e o controle de pestes e doen\u00e7as. Podar de um jeito impr\u00f3prio ou erroneamente poder\u00e1 afetar a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":176552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1431],"tags":[1460,1461],"class_list":["post-178569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidados","tag-rosas","tag-roseiras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuidados com Rosas - &nbsp;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidados com Rosas - &nbsp;\" \/>\n<meta property=\"og:description\" content=\"segunda, 26 de setembro de 2016 Texto e Foto: Christiane Calderan &#8211; Publicado por Raquel Patro no site O Jardineiro.net Podar envolve a remo\u00e7\u00e3o de qualquer rosa danificada, doente ou morta, para aprimorar a apar\u00eancia, estimulando o crescimento e o controle de pestes e doen\u00e7as. Podar de um jeito impr\u00f3prio ou erroneamente poder\u00e1 afetar a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/\" \/>\n<meta property=\"og:site_name\" content=\"Trapp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trappbrasiloficial\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-26T23:11:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T13:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"203\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mktgeral_trapp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mktgeral_trapp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/\"},\"author\":{\"name\":\"mktgeral_trapp\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/person\\\/479dbc846178e00476fcd10a4e92b3da\"},\"headline\":\"Cuidados com Rosas\",\"datePublished\":\"2016-09-26T23:11:22+00:00\",\"dateModified\":\"2024-11-08T13:31:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/\"},\"wordCount\":845,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/rosa2.jpg\",\"keywords\":[\"rosas\",\"roseiras\"],\"articleSection\":[\"Cuidados\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/\",\"name\":\"Cuidados com Rosas - &nbsp;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/rosa2.jpg\",\"datePublished\":\"2016-09-26T23:11:22+00:00\",\"dateModified\":\"2024-11-08T13:31:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/rosa2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/rosa2.jpg\",\"width\":200,\"height\":203},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/cuidados-com-rosas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.trapp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidados com Rosas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"name\":\"Trapp\",\"description\":\"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trapp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\",\"name\":\"Trapp\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"width\":165,\"height\":55,\"caption\":\"Trapp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/trappbrasiloficial\",\"https:\\\/\\\/www.instagram.com\\\/trapp_brasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/person\\\/479dbc846178e00476fcd10a4e92b3da\",\"name\":\"mktgeral_trapp\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/en\\\/author\\\/mktgeral_trapp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidados com Rosas - &nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/","og_locale":"en_US","og_type":"article","og_title":"Cuidados com Rosas - &nbsp;","og_description":"segunda, 26 de setembro de 2016 Texto e Foto: Christiane Calderan &#8211; Publicado por Raquel Patro no site O Jardineiro.net Podar envolve a remo\u00e7\u00e3o de qualquer rosa danificada, doente ou morta, para aprimorar a apar\u00eancia, estimulando o crescimento e o controle de pestes e doen\u00e7as. Podar de um jeito impr\u00f3prio ou erroneamente poder\u00e1 afetar a [&hellip;]","og_url":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/","og_site_name":"Trapp","article_publisher":"https:\/\/www.facebook.com\/trappbrasiloficial","article_published_time":"2016-09-26T23:11:22+00:00","article_modified_time":"2024-11-08T13:31:23+00:00","og_image":[{"width":200,"height":203,"url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg","type":"image\/jpeg"}],"author":"mktgeral_trapp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mktgeral_trapp","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#article","isPartOf":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/"},"author":{"name":"mktgeral_trapp","@id":"https:\/\/www.trapp.com.br\/#\/schema\/person\/479dbc846178e00476fcd10a4e92b3da"},"headline":"Cuidados com Rosas","datePublished":"2016-09-26T23:11:22+00:00","dateModified":"2024-11-08T13:31:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/"},"wordCount":845,"commentCount":0,"publisher":{"@id":"https:\/\/www.trapp.com.br\/#organization"},"image":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg","keywords":["rosas","roseiras"],"articleSection":["Cuidados"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/","url":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/","name":"Cuidados com Rosas - &nbsp;","isPartOf":{"@id":"https:\/\/www.trapp.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#primaryimage"},"image":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg","datePublished":"2016-09-26T23:11:22+00:00","dateModified":"2024-11-08T13:31:23+00:00","breadcrumb":{"@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trapp.com.br\/cuidados-com-rosas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#primaryimage","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/02\/rosa2.jpg","width":200,"height":203},{"@type":"BreadcrumbList","@id":"https:\/\/www.trapp.com.br\/cuidados-com-rosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.trapp.com.br\/"},{"@type":"ListItem","position":2,"name":"Cuidados com Rosas"}]},{"@type":"WebSite","@id":"https:\/\/www.trapp.com.br\/#website","url":"https:\/\/www.trapp.com.br\/","name":"Trapp","description":"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]","publisher":{"@id":"https:\/\/www.trapp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trapp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.trapp.com.br\/#organization","name":"Trapp","url":"https:\/\/www.trapp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","width":165,"height":55,"caption":"Trapp"},"image":{"@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trappbrasiloficial","https:\/\/www.instagram.com\/trapp_brasil"]},{"@type":"Person","@id":"https:\/\/www.trapp.com.br\/#\/schema\/person\/479dbc846178e00476fcd10a4e92b3da","name":"mktgeral_trapp","url":"https:\/\/www.trapp.com.br\/en\/author\/mktgeral_trapp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/comments?post=178569"}],"version-history":[{"count":1,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178569\/revisions"}],"predecessor-version":[{"id":179018,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178569\/revisions\/179018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/media\/176552"}],"wp:attachment":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/media?parent=178569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/categories?post=178569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/tags?post=178569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}