{"id":178965,"date":"2016-12-19T12:50:17","date_gmt":"2016-12-19T14:50:17","guid":{"rendered":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/"},"modified":"2024-11-08T10:27:33","modified_gmt":"2024-11-08T13:27:33","slug":"como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa","status":"publish","type":"post","link":"https:\/\/www.trapp.com.br\/en\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/","title":{"rendered":"Como cultivar uma flor do Natal no jardim ou em casa"},"content":{"rendered":"<div class=\"head-interna\"><span class=\"date\">segunda, 19 de dezembro de 2016<\/span><\/div>\n<div class=\"texto full-text\">\n<p>Conhecida por possuir v\u00e1rios nomes, a poins\u00e9tia ou flor do Natal, bico de papagaio ou ainda a estrela de bel\u00e9m, \u00e9 muito utilizada para fins decorativos, especialmente durante a \u00e9poca de Natal, devido \u00e0s suas p\u00e9talas de cor vermelha e folhas verdes. Esta planta, cujo per\u00edodo de flora\u00e7\u00e3o acontece entre Outubro e Fevereiro, exige uma elevada exposi\u00e7\u00e3o solar e deve-se proteger ao m\u00e1ximo das correntes de ar: descubra mais dicas acerca da poins\u00e9tia e cultive a sua pr\u00f3pria flor do Natal no jardim l\u00e1 de casa.<\/p>\n<p><strong>ORIGENS DA FLOR DO NATAL<\/strong><\/p>\n<p>O primeiro embaixador dos Estados Unidos da Am\u00e9rica no M\u00e9xico, Joel Roberts Poinsett, descobriu, nesse pa\u00eds, um exemplar da planta que viria a ser conhecida como \u201cflor do Natal\u201d. Em 1828, enviou alguns exemplares para a estufa da sua casa e, como se adaptaram muito bem, desenvolvendo-se com enorme facilidade, a planta ficou conhecida pelo nome do pr\u00f3prio embaixador: \u201cpoinsettia\u201d. Em portugu\u00eas chama-se poins\u00e9tia mas, ao longo dos anos, foi sendo apelidada de outros nome, hoje igualmente populares \u2013 flor do Natal ou bico de papagaio ou at\u00e9 mesmo estrela de bel\u00e9m. A verdade \u00e9 que, devido ao seu florescimento, que coincide precisamente com a \u00e9poca natal\u00edcia, a poins\u00e9tia come\u00e7ou a ser cada vez mais conhecida como a flor do Natal, ocupando um lugar de destaque na decora\u00e7\u00e3o da casa durante essa \u00e9poca festiva. Semi-lenhosa, com flores e folhas cuja textura assemelha-se \u00e0 pele, esta planta \u00e9 muitas vezes considerada um pequeno arbusto ou \u00e1rvore, que pode mesmo atingir entre 1 a 4 metros de altura. Com folhas largas e de cor verde escura, formam-se na ponta br\u00e1cteas vermelhas (nos mais diversos tons \u2013 do mais claro ao mais escuro), mas tamb\u00e9m existem poins\u00e9tias brancas, cor-de-rosa e alaranjadas. Ficariam bem no seu jardim?<\/p>\n<p><strong>COMO PLANTAR UMA POINS\u00c9TIA<\/strong><\/p>\n<p>Antes de plantar uma flor do Natal \u00e9 importante ter em conta 2 aspetos fundamentais: a poins\u00e9tia requer uma elevada exposi\u00e7\u00e3o solar (entre 6 e 8 horas de sol por dia) e deve estar devidamente protegida de eventuais correntes de ar. Escolhido o melhor local do jardim para a acolher, segue-se a planta\u00e7\u00e3o da flor do Natal:<\/p>\n<p>A parte do terreno escolhido para plantar a poins\u00e9tia deve ter um di\u00e2metro duas vezes maior que a raiz, por isso, tenha o cuidado de criar um buraco suficientemente grande.<br \/>\nColoque a poins\u00e9tia no buraco e junte a terra \u00e0 raiz, regando a base de seguida.<br \/>\nA cada duas semanas, fertilize a flor do Natal com adubo e \u00e1gua, aplicada exclusivamente na base da planta.<br \/>\nCaso opte por plantar a flor do Natal num vaso, para ter dentro de casa por exemplo, este tamb\u00e9m ter\u00e1 de ficar num local bastante luminoso, de prefer\u00eancia onde receba sol diariamente.<br \/>\nA terra ideal para plantar deve ser uma mistura arenosa e rica em mat\u00e9ria org\u00e2nica e a rega da flor do Natal deve ser efetuada apenas na ou a partir da altura em que o sol estiver a p\u00f4r-se.<br \/>\nPara manter uma poins\u00e9tia de pequena dimens\u00e3o dentro de casa, \u00e9 crucial ir podando a ponta dos galhos, o que ir\u00e1 estimular o seu florescimento e ajudar a manter a planta sempre composta.<\/p>\n<p><strong>COMO CUIDAR DE UMA FLOR DO NATAL<\/strong><\/p>\n<p>Esta planta, tal como todas as outras, precisa de cuidados para se manter bonita e saud\u00e1vel, por isso, quem tem ou quiser ter uma flor do Natal no jardim ou em casa deve saber que:<\/p>\n<p>A poins\u00e9tia \u00e9 uma planta que aprecia o sol e, mesmo em ambientes interiores, s\u00f3 se adapta bem a espa\u00e7os luminosos. N\u00e3o deve estar sujeita a correntes de ar ou temperaturas demasiado frias.<br \/>\nIdealmente, o melhor solo para o desenvolvimento da flor do Natal \u00e9 sempre um solo mais arenoso.<br \/>\nO estado do solo deve ser verificado com regularidade, regando-o sempre que se encontre seco, no entanto, tendo o cuidado de n\u00e3o regar em demasia, para n\u00e3o apodrecer a raiz.<br \/>\nQuanto \u00e0 fertiliza\u00e7\u00e3o, esta deve ser feita periodicamente, com recurso a adubo org\u00e2nico.<br \/>\n<strong>PERIGOS RELACIONADOS COM A POINS\u00c9TIA<\/strong><\/p>\n<p>Apesar da sua beleza e conota\u00e7\u00e3o natal\u00edcia, a flor do Natal \u00e9 uma planta extremamente t\u00f3xica para os seres humanos e considerada uma planta com propriedades venenosas. Ao entrar em contacto com a pele, a seiva leitosa da planta, que \u00e9 constitu\u00edda por uma esp\u00e9cie de l\u00e1tex, pode provocar inflama\u00e7\u00f5es, dor e comich\u00e3o, podendo at\u00e9 causar irrita\u00e7\u00e3o nos olhos, p\u00e1lpebras inchadas e dificuldade na vis\u00e3o. No caso de a planta ser ingerida, esta pode causar n\u00e1useas, v\u00f3mitos e diarreia, no entanto, e ao contr\u00e1rio do que \u00e9 normal comentar, esta planta n\u00e3o \u00e9 fatal. \u00c9 aconselhado evitar o contacto entre a poins\u00e9tia, as crian\u00e7as e\/ou animais de estima\u00e7\u00e3o.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg\" alt=\"\" \/><\/p>\n<p>Dispon\u00edvel em:\u00a0<a href=\"http:\/\/omeujardim.com\/artigos\/como-cultivar-flor-natal-jardim-casa\">O Meu Jardim<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>segunda, 19 de dezembro de 2016 Conhecida por possuir v\u00e1rios nomes, a poins\u00e9tia ou flor do Natal, bico de papagaio ou ainda a estrela de bel\u00e9m, \u00e9 muito utilizada para fins decorativos, especialmente durante a \u00e9poca de Natal, devido \u00e0s suas p\u00e9talas de cor vermelha e folhas verdes. Esta planta, cujo per\u00edodo de flora\u00e7\u00e3o acontece [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1555],"tags":[1443,1403],"class_list":["post-178965","post","type-post","status-publish","format-standard","hentry","category-jardinagem","tag-flores","tag-jardim"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;\" \/>\n<meta property=\"og:description\" content=\"segunda, 19 de dezembro de 2016 Conhecida por possuir v\u00e1rios nomes, a poins\u00e9tia ou flor do Natal, bico de papagaio ou ainda a estrela de bel\u00e9m, \u00e9 muito utilizada para fins decorativos, especialmente durante a \u00e9poca de Natal, devido \u00e0s suas p\u00e9talas de cor vermelha e folhas verdes. Esta planta, cujo per\u00edodo de flora\u00e7\u00e3o acontece [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Trapp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trappbrasiloficial\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-19T14:50:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T13:27:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg\" \/>\n<meta name=\"author\" content=\"mktgeral_trapp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mktgeral_trapp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/\"},\"author\":{\"name\":\"mktgeral_trapp\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/person\\\/479dbc846178e00476fcd10a4e92b3da\"},\"headline\":\"Como cultivar uma flor do Natal no jardim ou em casa\",\"datePublished\":\"2016-12-19T14:50:17+00:00\",\"dateModified\":\"2024-11-08T13:27:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/\"},\"wordCount\":836,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cultivar-flor-natal-jardim.jpg\",\"keywords\":[\"flores\",\"jardim\"],\"articleSection\":[\"Jardinagem\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/\",\"name\":\"Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cultivar-flor-natal-jardim.jpg\",\"datePublished\":\"2016-12-19T14:50:17+00:00\",\"dateModified\":\"2024-11-08T13:27:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cultivar-flor-natal-jardim.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cultivar-flor-natal-jardim.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.trapp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como cultivar uma flor do Natal no jardim ou em casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"name\":\"Trapp\",\"description\":\"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trapp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\",\"name\":\"Trapp\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"width\":165,\"height\":55,\"caption\":\"Trapp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/trappbrasiloficial\",\"https:\\\/\\\/www.instagram.com\\\/trapp_brasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/person\\\/479dbc846178e00476fcd10a4e92b3da\",\"name\":\"mktgeral_trapp\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/en\\\/author\\\/mktgeral_trapp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/","og_locale":"en_US","og_type":"article","og_title":"Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;","og_description":"segunda, 19 de dezembro de 2016 Conhecida por possuir v\u00e1rios nomes, a poins\u00e9tia ou flor do Natal, bico de papagaio ou ainda a estrela de bel\u00e9m, \u00e9 muito utilizada para fins decorativos, especialmente durante a \u00e9poca de Natal, devido \u00e0s suas p\u00e9talas de cor vermelha e folhas verdes. Esta planta, cujo per\u00edodo de flora\u00e7\u00e3o acontece [&hellip;]","og_url":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/","og_site_name":"Trapp","article_publisher":"https:\/\/www.facebook.com\/trappbrasiloficial","article_published_time":"2016-12-19T14:50:17+00:00","article_modified_time":"2024-11-08T13:27:33+00:00","og_image":[{"url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg","type":"","width":"","height":""}],"author":"mktgeral_trapp","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mktgeral_trapp","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#article","isPartOf":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/"},"author":{"name":"mktgeral_trapp","@id":"https:\/\/www.trapp.com.br\/#\/schema\/person\/479dbc846178e00476fcd10a4e92b3da"},"headline":"Como cultivar uma flor do Natal no jardim ou em casa","datePublished":"2016-12-19T14:50:17+00:00","dateModified":"2024-11-08T13:27:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/"},"wordCount":836,"commentCount":0,"publisher":{"@id":"https:\/\/www.trapp.com.br\/#organization"},"image":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg","keywords":["flores","jardim"],"articleSection":["Jardinagem"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/","url":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/","name":"Como cultivar uma flor do Natal no jardim ou em casa - &nbsp;","isPartOf":{"@id":"https:\/\/www.trapp.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#primaryimage"},"image":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg","datePublished":"2016-12-19T14:50:17+00:00","dateModified":"2024-11-08T13:27:33+00:00","breadcrumb":{"@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#primaryimage","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2024\/11\/cultivar-flor-natal-jardim.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trapp.com.br\/como-cultivar-uma-flor-do-natal-no-jardim-ou-em-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.trapp.com.br\/"},{"@type":"ListItem","position":2,"name":"Como cultivar uma flor do Natal no jardim ou em casa"}]},{"@type":"WebSite","@id":"https:\/\/www.trapp.com.br\/#website","url":"https:\/\/www.trapp.com.br\/","name":"Trapp","description":"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]","publisher":{"@id":"https:\/\/www.trapp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trapp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.trapp.com.br\/#organization","name":"Trapp","url":"https:\/\/www.trapp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","width":165,"height":55,"caption":"Trapp"},"image":{"@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trappbrasiloficial","https:\/\/www.instagram.com\/trapp_brasil"]},{"@type":"Person","@id":"https:\/\/www.trapp.com.br\/#\/schema\/person\/479dbc846178e00476fcd10a4e92b3da","name":"mktgeral_trapp","url":"https:\/\/www.trapp.com.br\/en\/author\/mktgeral_trapp\/"}]}},"_links":{"self":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/comments?post=178965"}],"version-history":[{"count":1,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178965\/revisions"}],"predecessor-version":[{"id":179359,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/posts\/178965\/revisions\/179359"}],"wp:attachment":[{"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/media?parent=178965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/categories?post=178965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trapp.com.br\/en\/wp-json\/wp\/v2\/tags?post=178965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}