{"id":1624,"date":"2024-10-01T14:27:37","date_gmt":"2024-10-01T17:27:37","guid":{"rendered":"https:\/\/www.trapp.com.br\/post_produto\/ts-3144-205cm\/"},"modified":"2025-08-11T14:23:28","modified_gmt":"2025-08-11T17:23:28","slug":"ts-3144-205cm","status":"publish","type":"post_produto","link":"https:\/\/www.trapp.com.br\/es\/produto\/ts-3144-205cm\/","title":{"rendered":"TS 3144 | 20,5cm"},"content":{"rendered":"<p>Capacidad de corte: \u00d81,8 mm.<br \/>\nL\u00e1mina superior de acero de alto carbono. L\u00e1mina inferior de acero de medio carbono cromado.<br \/>\nMango anat\u00f3mico de nailon y fibra de vidrio, con empu\u00f1aduras recubiertas con antideslizante suave.<br \/>\nBloqueo de seguridad para mantener la tijera cerrada.<\/p>\n<p><strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Aplicaci\u00f3n:&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:957,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0}\">Aplicaci\u00f3n:<\/span><\/strong><br \/>\nIdeal para podar flores, follajes y tallos de hasta 1,8 cm de espesor.<\/p>","protected":false},"excerpt":{"rendered":"<p>Capacidad de corte: \u00d81,8 mm. L\u00e1mina superior de acero de alto carbono. L\u00e1mina inferior de acero de medio carbono cromado. Mango anat\u00f3mico de nailon y fibra de vidrio, con empu\u00f1aduras recubiertas con antideslizante suave. Bloqueo de seguridad para mantener la tijera cerrada. Aplicaci\u00f3n: Ideal para podar flores, follajes y tallos de hasta 1,8 cm de [&hellip;]<\/p>\n","protected":false},"featured_media":1625,"template":"","meta":{"_acf_changed":false},"tax_produto_aplicacao":[],"tax_produto_categoria":[199,272],"tax_produto_tag":[],"class_list":["post-1624","post_produto","type-post_produto","status-publish","has-post-thumbnail","hentry","tax_produto_categoria-ferramentas","tax_produto_categoria-linha-pode-e-corte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TS 3144 | 20,5cm -&nbsp;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TS 3144 | 20,5cm -&nbsp;\" \/>\n<meta property=\"og:description\" content=\"Capacidad de corte: \u00d81,8 mm. L\u00e1mina superior de acero de alto carbono. L\u00e1mina inferior de acero de medio carbono cromado. Mango anat\u00f3mico de nailon y fibra de vidrio, con empu\u00f1aduras recubiertas con antideslizante suave. Bloqueo de seguridad para mantener la tijera cerrada. Aplicaci\u00f3n: Ideal para podar flores, follajes y tallos de hasta 1,8 cm de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Trapp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trappbrasiloficial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T17:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/03\/ts-3144.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/\",\"name\":\"TS 3144 | 20,5cm -&nbsp;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ts-3144.jpg\",\"datePublished\":\"2024-10-01T17:27:37+00:00\",\"dateModified\":\"2025-08-11T17:23:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ts-3144.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ts-3144.jpg\",\"width\":720,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/produto\\\/ts-3144-205cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.trapp.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TS 3144 | 20,5cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"name\":\"Trapp\",\"description\":\"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trapp.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#organization\",\"name\":\"Trapp\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"contentUrl\":\"https:\\\/\\\/www.trapp.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/trapp.png\",\"width\":165,\"height\":55,\"caption\":\"Trapp\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trapp.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/trappbrasiloficial\",\"https:\\\/\\\/www.instagram.com\\\/trapp_brasil\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TS 3144 | 20,5cm -&nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/","og_locale":"es_ES","og_type":"article","og_title":"TS 3144 | 20,5cm -&nbsp;","og_description":"Capacidad de corte: \u00d81,8 mm. L\u00e1mina superior de acero de alto carbono. L\u00e1mina inferior de acero de medio carbono cromado. Mango anat\u00f3mico de nailon y fibra de vidrio, con empu\u00f1aduras recubiertas con antideslizante suave. Bloqueo de seguridad para mantener la tijera cerrada. Aplicaci\u00f3n: Ideal para podar flores, follajes y tallos de hasta 1,8 cm de [&hellip;]","og_url":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/","og_site_name":"Trapp","article_publisher":"https:\/\/www.facebook.com\/trappbrasiloficial","article_modified_time":"2025-08-11T17:23:28+00:00","og_image":[{"width":720,"height":481,"url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/03\/ts-3144.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/","url":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/","name":"TS 3144 | 20,5cm -&nbsp;","isPartOf":{"@id":"https:\/\/www.trapp.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/#primaryimage"},"image":{"@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/03\/ts-3144.jpg","datePublished":"2024-10-01T17:27:37+00:00","dateModified":"2025-08-11T17:23:28+00:00","breadcrumb":{"@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/#primaryimage","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/03\/ts-3144.jpg","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2022\/03\/ts-3144.jpg","width":720,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/www.trapp.com.br\/produto\/ts-3144-205cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.trapp.com.br\/"},{"@type":"ListItem","position":2,"name":"TS 3144 | 20,5cm"}]},{"@type":"WebSite","@id":"https:\/\/www.trapp.com.br\/#website","url":"https:\/\/www.trapp.com.br\/","name":"Trapp","description":"[:pb]Cultivando o amor pela terra.[:en]Cultivating love for the earth.[:es]Cultivando el amor por la tierra.[:]","publisher":{"@id":"https:\/\/www.trapp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trapp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.trapp.com.br\/#organization","name":"Trapp","url":"https:\/\/www.trapp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","contentUrl":"https:\/\/www.trapp.com.br\/wp-content\/uploads\/2025\/04\/trapp.png","width":165,"height":55,"caption":"Trapp"},"image":{"@id":"https:\/\/www.trapp.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trappbrasiloficial","https:\/\/www.instagram.com\/trapp_brasil"]}]}},"_links":{"self":[{"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/post_produto\/1624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/post_produto"}],"about":[{"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/types\/post_produto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/media\/1625"}],"wp:attachment":[{"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/media?parent=1624"}],"wp:term":[{"taxonomy":"tax_produto_aplicacao","embeddable":true,"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/tax_produto_aplicacao?post=1624"},{"taxonomy":"tax_produto_categoria","embeddable":true,"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/tax_produto_categoria?post=1624"},{"taxonomy":"tax_produto_tag","embeddable":true,"href":"https:\/\/www.trapp.com.br\/es\/wp-json\/wp\/v2\/tax_produto_tag?post=1624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}